{"id":38912,"date":"2023-12-05T09:00:00","date_gmt":"2023-12-05T08:00:00","guid":{"rendered":"https:\/\/difue.de\/?p=38912"},"modified":"2023-12-05T08:40:35","modified_gmt":"2023-12-05T07:40:35","slug":"bei-wikipedia-mitmachen","status":"publish","type":"post","link":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/","title":{"rendered":"Mitmachen bei Wikipedia: So geht\u2019s!"},"content":{"rendered":" <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Mehr als <a href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/195081\/umfrage\/anzahl-der-artikel-auf-wikipedia-weltweit\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">61 Millionen Artikel<\/a> und <a href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/1021463\/umfrage\/anzahl-der-visits-pro-monat-von-wikipediaorg\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">4,4 Milliarden Visits allein im August 2023<\/a>: Wikipedia ist die wahrscheinlich bekannteste Online-Enzyklop\u00e4die. Der Clou an Wikipedia? Grunds\u00e4tzlich k\u00f6nnen alle die dort ver\u00f6ffentlichten Artikel bearbeiten. Und das macht die Wikipedia-Community auch flei\u00dfig: Im Schnitt wurden im Januar 2023 knapp sechs Bearbeitungen pro Sekunde vorgenommen, was sich auf 15 Millionen Bearbeitungen weltweit pro Monat l\u00e4ppert.&nbsp;<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-wie-kann-man-artikel-bearbeiten\">Wie kann man Artikel bearbeiten?<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Wer bei Wikipedia mitschreiben m\u00f6chte, kann sich registrieren, muss es aber nicht. Denn auch ohne Anmeldung lassen sich Artikel bearbeiten. Mit einem Klick auf die Schaltfl\u00e4che \u201eBearbeiten\u201c in der Kopfleiste eines beliebigen Artikels wird die Bearbeitungsansicht aktiviert:<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"wp-block-image\"> <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png\"><img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"231\" src=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png\" alt=\"\" class=\"wp-image-38914\" srcset=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png 459w, https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia-300x151.png 300w, https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia-340x170.png 340w, https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia-150x75.png 150w, https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia-400x201.png 400w\" sizes=\"auto, (max-width: 459px) 100vw, 459px\" \/><\/a><\/figure>\n<\/div><\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Text\u00e4nderungen k\u00f6nnen nun einfach direkt in den Text eingef\u00fcgt werden. Anschlie\u00dfend klickt man auf \u201e\u00c4nderungen ver\u00f6ffentlichen\u201c.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-werden-anderungen-direkt-veroffentlicht\">Werden \u00c4nderungen direkt ver\u00f6ffentlicht?&nbsp;<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>\u00c4nderungen sind h\u00e4ufig nicht direkt sichtbar. Insbesondere bei Artikeln oder Anpassungen von unregistrierten und neuen Nutzer:innen landen diese zun\u00e4chst in der sogenannten <em>Sichtung<\/em>: Hier werden die neuen Inhalte von erfahrenen Wikipedianer:innen gepr\u00fcft \u2013 zum Beispiel auf Rechtschreibfehler, Quellenangaben und enzyklop\u00e4dische Relevanz. Wer \u00c4nderungen vorgenommen hat, die abgelehnt wurden, kann im Tab \u201eDiskussion\u201c (links oben) f\u00fcr die eigene Sache argumentieren.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Einfacher wird es, wenn man selbst ein sogenannter <em>Sichter<\/em> wird und eigene \u00c4nderungen ungepr\u00fcft ver\u00f6ffentlichen kann. Neben der Registrierung gibt es eine Reihe von <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Gesichtete_Versionen#Sichterstatus\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Voraussetzungen<\/a>, die f\u00fcr die Vergabe des Sichterstatus erf\u00fcllt sein m\u00fcssen.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-vorteile-der-registrierung\">Vorteile der Registrierung<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Obwohl man auch ohne Registrierung bei Wikipedia mitmachen kann, empfiehlt die Wikipedia-Community, ein Benutzerkonto anzulegen. Dabei kann man sich kostenlos anmelden und mit einem Benutzernamen registrieren.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Registrierte genie\u00dfen einige Vorteile, unter anderem:<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<ul class=\"wp-block-list\"> <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-12 offset-lg-0\">\t\n<li>Mehr Anonymit\u00e4t (Statt der verwendeten IP-Adresse wird nur der selbstgew\u00e4hlte Benutzername \u00f6ffentlich angezeigt)<\/li>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-12 offset-lg-0\">\t\n<li>Man kann einfacher mit anderen Nutzer:innen in Kontakt treten<\/li>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-12 offset-lg-0\">\t\n<li>Nach vier Tagen werden registrierte Nutzer:innen zu sogenannten <em>automatisch best\u00e4tigten Benutzern<\/em>. Als solche k\u00f6nnen sie nicht nur Artikel bearbeiten, sondern unter anderem auch Seiten verschieben oder Dateien hochladen.<\/li>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-12 offset-lg-0\">\t\n<li>Artikel lassen sich auf eine Beobachtungsliste setzen<\/li>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-12 offset-lg-0\">\t\n<li>Andere Benutzer:innen k\u00f6nnen ein kleines \u201eDankesch\u00f6n\u201c f\u00fcr hilfreiche \u00c4nderungen hinterlassen<\/li>\n<\/div><\/div><\/div><\/ul>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-vandalismus-bei-wikipedia\">Vandalismus bei Wikipedia<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Einige Artikel k\u00f6nnen ausschlie\u00dflich von angemeldeten Nutzer:innen bearbeitet werden. Oft handelt es sich um Artikel zu kontroversen Themen, bei denen immer wieder Inhalte vors\u00e4tzlich gel\u00f6scht oder falsche Inhalte hinzugef\u00fcgt werden. Dieses Verhalten wird bei Wikipedia als <em>Vandalismus <\/em>bezeichnet \u2013 denn auch bei Wikipedia treiben Trolle ihr Unwesen.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Dagegen geht Wikipedia vor, indem die Administratoren (kurz \u201eAdmins\u201c) ausgew\u00e4hlte Inhalte f\u00fcr einen bestimmten Zeitraum vor der Bearbeitung sch\u00fctzen. Sind Artikel dauerhaft von Vandalismus betroffen, werden sie auch dauerhaft gesch\u00fctzt. Beispiele daf\u00fcr sind die <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Liste_der_am_l%C3%A4ngsten_gesch%C3%BCtzten_Artikel\/autoconfirmed\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Eintr\u00e4ge zu Angela Merkel, Abraham Lincoln und Cem \u00d6zdemir<\/a>.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-wann-ist-ein-thema-fur-wikipedia-relevant\">Wann ist ein Thema f\u00fcr Wikipedia relevant?<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Wie wird aber eigentlich festgelegt, wann ein Thema oder eine Person auf Wikipedia einen Eintrag erh\u00e4lt? Daf\u00fcr gibt es <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Relevanzkriterien\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Richtlinien und Kriterien<\/a>, anhand derer entschieden wird, ob ein Thema f\u00fcr Wikipedia relevant ist. Relevant sind zum Beispiel Personen, Ereignisse oder Themen, die eine breite \u00d6ffentlichkeitswirkung haben, die wahrscheinlich andauert: Ein Artikel \u00fcber die ehemalige Bundeskanzlerin w\u00fcrde demnach wahrscheinlich als relevant eingeordnet.&nbsp;<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Au\u00dferdem kann man, bevor man einen neuen Artikel anlegt, einen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Relevanzcheck\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Relevanzcheck<\/a> starten:<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"wp-block-image\"> <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/relevanzcheck.png\"><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"175\" src=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/relevanzcheck.png\" alt=\"\" class=\"wp-image-38915\" srcset=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/relevanzcheck.png 602w, https:\/\/difue.de\/app\/uploads\/2023\/11\/relevanzcheck-300x87.png 300w, https:\/\/difue.de\/app\/uploads\/2023\/11\/relevanzcheck-150x44.png 150w, https:\/\/difue.de\/app\/uploads\/2023\/11\/relevanzcheck-400x116.png 400w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/a><\/figure>\n<\/div><\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Hier lassen sich m\u00f6gliche Quellen und Argumente vorbringen, die daf\u00fcrsprechen, dass ein Artikel f\u00fcr Wikipedia relevant sein k\u00f6nnte. Diese werden dann von anderen Wikipedia-Nutzer:innen gepr\u00fcft.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-wer-macht-bei-der-wikipedia-mit\">Wer macht bei der Wikipedia mit?<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Obwohl jeder Mensch mit einem internetf\u00e4higen Endger\u00e4t an der Wikipedia mitarbeiten kann, gibt es Ungleichgewichte bei den Eintr\u00e4gen und Benutzer:innen. <a href=\"https:\/\/www.sueddeutsche.de\/digital\/wikipedia-frauen-maenner-1.5173285\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">F\u00fcnf von sechs Biografien bei Wikipedia weltweit<\/a> behandeln M\u00e4nner und <a href=\"https:\/\/de.wikipedia.org\/wiki\/Geschlechterverteilung_in_der_Wikipedia\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">neun von zehn Personen<\/a>, die weltweit in Projekten der Dachorganisation Wikimedia mitwirken, sind m\u00e4nnlich. Wer das \u00e4ndern m\u00f6chte, kann jederzeit einsteigen und mitmachen \u2013 unabh\u00e4ngig von Geschlecht, Alter oder anderen Merkmalen.<\/p>\n<\/div><\/div><\/div>\n\n\n<section class=\"block__cta text-align-center mb-6\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12 col-lg-4 offset-lg-4\">\n\t\t\t\t<a href=\"https:\/\/difue.de\/lernzentrale\/privat\/level3\/internet\/web-web-2-0\/\"><div class=\"block__cta__cta_wrapper fw-bold \">\n\t\t\t\t\tHier geht&#8217;s zum Zertifikat!\t\t\t\t<\/div><\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"row mt-6\">\n\t\t\t\t<div class=\"col-12 col-lg-4 offset-lg-4\">\n\t\t\t\t\t<div class=\"block__cta__text_wrapper\">\n\t\t\t\t\t\tVon Wikipedia bis WWW: Beim Digitalf\u00fchrerschein kannst du dein Wissen rund ums Internet, Datenschutz- und sicherheit erweitern und direkt zertifizieren lassen. \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section>\n\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p><strong>Artikelbild: Oberon Copeland @veryinformed.com via <a href=\"https:\/\/unsplash.com\/de\/fotos\/einen-computerbildschirm-mit-einer-liste-EtCxIuaG-zU\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">unsplash.com<\/a><\/strong><\/p>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Mehr als 61 Millionen Artikel und 4,4 Milliarden Visits allein im August 2023: Wikipedia ist die wahrscheinlich bekannteste Online-Enzyklop\u00e4die. Der [&hellip;]<\/p>\n","protected":false},"author":8048,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[453,7],"tags":[67,438],"class_list":["post-38912","post","type-post","status-publish","format-standard","hentry","category-devices-tools","category-internet","tag-internet","tag-wikipedia"],"acf":{"show_similar_posts":"Ja","similar_posts":[15395,33760],"sleeve":"","kicker":"Internet-Lexikon","bild":38919,"bildunterschrift":"Wikipedia-Eintrag \u00fcber Wikipedia","anreisser":"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?","podcast":"","video":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mitmachen bei Wikipedia: So geht\u2019s! &#8226; Digitalf\u00fchrerschein (DiF\u00fc)<\/title>\n<meta name=\"description\" content=\"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitmachen bei Wikipedia: So geht\u2019s!\" \/>\n<meta property=\"og:description\" content=\"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/\" \/>\n<meta property=\"og:site_name\" content=\"Digitalf\u00fchrerschein (DiF\u00fc)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/DsiN-Digitalf%c3%bchrerschein-DiF%c3%bc\/100079074183260\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-05T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/difue.de\/app\/uploads\/2023\/11\/difue-news-wikipedia-mitmachen.jpg\" \/><meta property=\"og:image:width\" content=\"1080\" \/><meta property=\"og:image:height\" content=\"768\" \/><meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DiF\u00fc-Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DiF\u00fc-Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/\"},\"author\":{\"name\":\"DiF\u00fc-Redaktion\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#\\\/schema\\\/person\\\/561da257ed73a0e0a7b309ed668c2e2f\"},\"headline\":\"Mitmachen bei Wikipedia: So geht\u2019s!\",\"datePublished\":\"2023-12-05T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/\"},\"wordCount\":661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/difue.de\\\/app\\\/uploads\\\/2023\\\/11\\\/wikipedia.png\",\"keywords\":[\"Internet\",\"Wikipedia\"],\"articleSection\":[\"Devices &amp; Tools\",\"Internet\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/\",\"url\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/\",\"name\":\"Mitmachen bei Wikipedia: So geht\u2019s! &#8226; Digitalf\u00fchrerschein (DiF\u00fc)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/difue.de\\\/app\\\/uploads\\\/2023\\\/11\\\/wikipedia.png\",\"datePublished\":\"2023-12-05T08:00:00+00:00\",\"description\":\"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/difue.de\\\/app\\\/uploads\\\/2023\\\/11\\\/wikipedia.png\",\"contentUrl\":\"https:\\\/\\\/difue.de\\\/app\\\/uploads\\\/2023\\\/11\\\/wikipedia.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/news\\\/internet\\\/bei-wikipedia-mitmachen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/difue.de\\\/en\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitmachen bei Wikipedia: So geht\u2019s!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/difue.de\\\/en\\\/\",\"name\":\"Digitalf\u00fchrerschein (DiF\u00fc)\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/difue.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#organization\",\"name\":\"Digitalf\u00fchrerschein (DiF\u00fc)\",\"url\":\"https:\\\/\\\/difue.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/difue.de\\\/app\\\/uploads\\\/2021\\\/09\\\/difue-logo.svg\",\"contentUrl\":\"https:\\\/\\\/difue.de\\\/app\\\/uploads\\\/2021\\\/09\\\/difue-logo.svg\",\"width\":200,\"height\":149,\"caption\":\"Digitalf\u00fchrerschein (DiF\u00fc)\"},\"image\":{\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/DsiN-Digitalf\u00fchrerschein-DiF\u00fc\\\/100079074183260\\\/\",\"https:\\\/\\\/www.instagram.com\\\/dsin_digitalfuehrerschein\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/difue.de\\\/en\\\/#\\\/schema\\\/person\\\/561da257ed73a0e0a7b309ed668c2e2f\",\"name\":\"DiF\u00fc-Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g\",\"caption\":\"DiF\u00fc-Redaktion\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mitmachen bei Wikipedia: So geht\u2019s! &#8226; Digitalf\u00fchrerschein (DiF\u00fc)","description":"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/","og_locale":"en_US","og_type":"article","og_title":"Mitmachen bei Wikipedia: So geht\u2019s!","og_description":"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?","og_url":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/","og_site_name":"Digitalf\u00fchrerschein (DiF\u00fc)","article_publisher":"https:\/\/www.facebook.com\/people\/DsiN-Digitalf%c3%bchrerschein-DiF%c3%bc\/100079074183260\/","article_published_time":"2023-12-05T08:00:00+00:00","author":"DiF\u00fc-Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DiF\u00fc-Redaktion","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#article","isPartOf":{"@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/"},"author":{"name":"DiF\u00fc-Redaktion","@id":"https:\/\/difue.de\/en\/#\/schema\/person\/561da257ed73a0e0a7b309ed668c2e2f"},"headline":"Mitmachen bei Wikipedia: So geht\u2019s!","datePublished":"2023-12-05T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/"},"wordCount":661,"commentCount":0,"publisher":{"@id":"https:\/\/difue.de\/en\/#organization"},"image":{"@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#primaryimage"},"thumbnailUrl":"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png","keywords":["Internet","Wikipedia"],"articleSection":["Devices &amp; Tools","Internet"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/","url":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/","name":"Mitmachen bei Wikipedia: So geht\u2019s! &#8226; Digitalf\u00fchrerschein (DiF\u00fc)","isPartOf":{"@id":"https:\/\/difue.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#primaryimage"},"image":{"@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#primaryimage"},"thumbnailUrl":"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png","datePublished":"2023-12-05T08:00:00+00:00","description":"Beim bekanntesten Nachschlagewerk der Welt kann prinzipiell jeder Eintr\u00e4ge erstellen. Wie kann man bei Wikipedia mitmachen?","breadcrumb":{"@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#primaryimage","url":"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png","contentUrl":"https:\/\/difue.de\/app\/uploads\/2023\/11\/wikipedia.png"},{"@type":"BreadcrumbList","@id":"https:\/\/difue.de\/en\/news\/internet\/bei-wikipedia-mitmachen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/difue.de\/en\/startseite\/"},{"@type":"ListItem","position":2,"name":"Mitmachen bei Wikipedia: So geht\u2019s!"}]},{"@type":"WebSite","@id":"https:\/\/difue.de\/en\/#website","url":"https:\/\/difue.de\/en\/","name":"Digitalf\u00fchrerschein (DiF\u00fc)","description":"","publisher":{"@id":"https:\/\/difue.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/difue.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/difue.de\/en\/#organization","name":"Digitalf\u00fchrerschein (DiF\u00fc)","url":"https:\/\/difue.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/difue.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/difue.de\/app\/uploads\/2021\/09\/difue-logo.svg","contentUrl":"https:\/\/difue.de\/app\/uploads\/2021\/09\/difue-logo.svg","width":200,"height":149,"caption":"Digitalf\u00fchrerschein (DiF\u00fc)"},"image":{"@id":"https:\/\/difue.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/DsiN-Digitalf\u00fchrerschein-DiF\u00fc\/100079074183260\/","https:\/\/www.instagram.com\/dsin_digitalfuehrerschein\/"]},{"@type":"Person","@id":"https:\/\/difue.de\/en\/#\/schema\/person\/561da257ed73a0e0a7b309ed668c2e2f","name":"DiF\u00fc-Redaktion","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g","caption":"DiF\u00fc-Redaktion"}}]}},"_links":{"self":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/38912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/users\/8048"}],"replies":[{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/comments?post=38912"}],"version-history":[{"count":18,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/38912\/revisions"}],"predecessor-version":[{"id":39048,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/38912\/revisions\/39048"}],"acf:post":[{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/33760"},{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/15395"}],"wp:attachment":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/media?parent=38912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/categories?post=38912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/tags?post=38912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}