{"id":39288,"date":"2023-12-14T08:00:00","date_gmt":"2023-12-14T07:00:00","guid":{"rendered":"https:\/\/difue.de\/?p=39288"},"modified":"2023-12-14T10:59:13","modified_gmt":"2023-12-14T09:59:13","slug":"mythos-des-monats-digital-natives","status":"publish","type":"post","link":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/","title":{"rendered":"Je j\u00fcnger, desto digitaler \u2013 stimmt das?"},"content":{"rendered":" <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Schon einmal versucht, einem \u00e4lteren Familienmitglied zu zeigen, wie ein Doppelklick funktioniert? Dass es nicht <em>Klick<\/em> \u2026 <em>Klick<\/em>, sondern <em>KlickKlick<\/em> hei\u00dfen muss?<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Im Umgang mit Technologie werden Generationsunterschiede besonders sichtbar. Und wenn die nachfolgende Generation alt genug ist, um ein Smartphone zu halten, sieht man selbst pl\u00f6tzlich alt aus.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-die-gen-z-und-das-internet-sind-sie-die-wahren-digital-natives\">Die Gen Z und das Internet: Sind sie die wahren Digital Natives?<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Besonders die Gen Z, also diejenigen, die nach 1996 geboren sind, gelten als besonders technisch versiert. Das liegt unter anderem daran, dass sie sich wahrscheinlich nicht an eine Welt erinnern k\u00f6nnen, in der es keine Handys, kein Internet und keine Form von sozialen Medien gibt. Medial und gesellschaftlich wird die Gen Z deswegen h\u00e4ufig als besonders technisch versiert und die wahren Digital Natives dargestellt.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Gute Nachrichten, insbesondere f\u00fcr Unternehmen, denn <a href=\"https:\/\/www.weforum.org\/agenda\/2022\/05\/gen-z-don-t-want-to-work-for-you-here-s-how-to-change-their-mind\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" class=\"broken_link\">bis 2025 soll die Genz Z fast ein Drittel der weltweiten Arbeitskraft stellen.<\/a> Oder?<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p><a href=\"https:\/\/www.forbes.com\/sites\/forbestechcouncil\/2023\/06\/23\/the-next-generation-of-workers-is-less-tech-savvy-than-we-may-think\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Aktuelle Studien<\/a> zeigen, dass eine Mehrheit der befragten Gen Zler kaum bis keine Ausbildung in Sachen digitale Kenntnisse erhalten haben. Viele bem\u00e4ngeln insbesondere ein Fehlen von digitalen Schwerpunkten in der Schule.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-digitale-kindheit-digitalkompetenzen\">Digitale Kindheit = Digitalkompetenzen?<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Zahlen aus Deutschland malen ein \u00e4hnliches Bild: Die <a href=\"https:\/\/www.vodafone-stiftung.de\/jugendstudie-kompetenzen-2023\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Jugendstudie der Vodafone-Stiftung<\/a> aus dem Fr\u00fchjahr 2023 ergibt: Rund 70 Prozent der Berufseinsteigenden f\u00fchlen sich nicht fit f\u00fcr die digitale Arbeitswelt. So verwundert es auch nicht, dass mehr als die H\u00e4lfte der Jugendlichen unsicher sind, wie sie die eigenen Daten im Internet am besten sch\u00fctzen k\u00f6nnen. &nbsp;<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Sich im digitalen Raum sicher und souver\u00e4n zu bewegen, ist nicht mehr K\u00fcr, sondern Pflicht: Dabei kommt nicht nur Eltern, sondern <a href=\"https:\/\/difue.de\/news\/schule-digitalisierung-it-sicherheit\/\" target=\"_blank\" rel=\"noreferrer noopener\">auch Schulen und anderen Bildungseinrichtungen eine wichtige Bedeutung<\/a> zu. Doch gerade dort sehen viele der Befragten noch Nachholbedarf: Nur knapp die H\u00e4lfte der 14- bis 24-J\u00e4hrigen beurteilt die digitale Ausstattung ihrer Schulen als sehr gut oder gut.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<h2 class=\"wp-block-heading\" id=\"h-fazit-digital-aufgewachsen-heisst-nicht-gleich-digital-kompetent\">Fazit? Digital aufgewachsen hei\u00dft nicht gleich digital kompetent<\/h2>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Die Gen Z und die darauffolgende Generation Alpha sind zwar so wie keine Generation zuvor mit digitalen Medien und Ger\u00e4ten aufgewachsen. Das allein reicht aber nicht aus, sondern muss mit digitaler Bildung flankiert werden: Digitalkompetenzen m\u00fcssen, \u00e4hnlich wie Lesen, Schreiben oder Rechnen gelehrt und gelernt werden.<\/p>\n<\/div><\/div><\/div>\n\n <div class=\"container  post_type__post\"><div class=\"row mb-3\"><div class=\"col-12 col-lg-8 offset-lg-2\">\t\n<p>Die Antwort auf den Mythos <em>je j\u00fcnger desto digitaler<\/em> ist also ein ja, aber \u2026 Ja, j\u00fcngere Generationen k\u00f6nnen vielleicht intuitiver mit Ger\u00e4ten und Anwendungen umgehen, sind aber nicht automatisch digital kompetent. Hier m\u00fcssen Gro\u00df und Klein am Ball bleiben.<\/p>\n<\/div><\/div><\/div>\n\n\n<section class=\"block__cta text-align-center mb-6\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12 col-lg-4 offset-lg-4\">\n\t\t\t\t<a href=\"https:\/\/difue.de\/lernzentrale\/\"><div class=\"block__cta__cta_wrapper fw-bold \">\n\t\t\t\t\tHier geht&#8217;s zum DiF\u00fc!\t\t\t\t<\/div><\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"row mt-6\">\n\t\t\t\t<div class=\"col-12 col-lg-4 offset-lg-4\">\n\t\t\t\t\t<div class=\"block__cta__text_wrapper\">\n\t\t\t\t\t\tDigitalkompetenzen to Go? Gibt\u2019s beim DiF\u00fc: Individuell und kostenfrei das eigene Wissen testen \u2013 und direkt zertifizieren lassen.  \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Schon einmal versucht, einem \u00e4lteren Familienmitglied zu zeigen, wie ein Doppelklick funktioniert? Dass es nicht Klick \u2026 Klick, sondern KlickKlick [&hellip;]<\/p>\n","protected":false},"author":8048,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[453,425],"tags":[384,67,74],"class_list":["post-39288","post","type-post","status-publish","format-standard","hentry","category-devices-tools","category-mythos-des-monats","tag-digitalkompetenzen","tag-internet","tag-social-media"],"acf":{"show_similar_posts":"Ja","similar_posts":[39421],"sleeve":"","kicker":"Digital Natives","bild":39292,"bildunterschrift":"Zwei Junge Frauen mit Smartphones","anreisser":"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich? ","podcast":"","video":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v24.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Je j\u00fcnger, desto digitaler \u2013 stimmt das? &#8226; Digitalf\u00fchrerschein (DiF\u00fc)<\/title>\n<meta name=\"description\" content=\"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je j\u00fcnger, desto digitaler \u2013 stimmt das?\" \/>\n<meta property=\"og:description\" content=\"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\" \/>\n<meta property=\"og:site_name\" content=\"Digitalf\u00fchrerschein (DiF\u00fc)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/DsiN-Digitalf%c3%bchrerschein-DiF%c3%bc\/100079074183260\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T09:59:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/difue.de\/app\/uploads\/2023\/12\/Gen-Z-digital-Natives.jpg\" \/><meta property=\"og:image:width\" content=\"1080\" \/><meta property=\"og:image:height\" content=\"754\" \/><meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DiF\u00fc-Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DiF\u00fc-Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\"},\"author\":{\"name\":\"DiF\u00fc-Redaktion\",\"@id\":\"https:\/\/difue.de\/en\/#\/schema\/person\/561da257ed73a0e0a7b309ed668c2e2f\"},\"headline\":\"Je j\u00fcnger, desto digitaler \u2013 stimmt das?\",\"datePublished\":\"2023-12-14T07:00:00+00:00\",\"dateModified\":\"2023-12-14T09:59:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\"},\"wordCount\":411,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/difue.de\/en\/#organization\"},\"keywords\":[\"Digitalkompetenzen\",\"Internet\",\"Social Media\"],\"articleSection\":[\"Devices &amp; Tools\",\"Mythos des Monats\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\",\"url\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\",\"name\":\"Je j\u00fcnger, desto digitaler \u2013 stimmt das? &#8226; Digitalf\u00fchrerschein (DiF\u00fc)\",\"isPartOf\":{\"@id\":\"https:\/\/difue.de\/en\/#website\"},\"datePublished\":\"2023-12-14T07:00:00+00:00\",\"dateModified\":\"2023-12-14T09:59:13+00:00\",\"description\":\"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich?\",\"breadcrumb\":{\"@id\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/difue.de\/en\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Je j\u00fcnger, desto digitaler \u2013 stimmt das?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/difue.de\/en\/#website\",\"url\":\"https:\/\/difue.de\/en\/\",\"name\":\"Digitalf\u00fchrerschein (DiF\u00fc)\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/difue.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/difue.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/difue.de\/en\/#organization\",\"name\":\"Digitalf\u00fchrerschein (DiF\u00fc)\",\"url\":\"https:\/\/difue.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/difue.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/difue.de\/app\/uploads\/2021\/09\/difue-logo.svg\",\"contentUrl\":\"https:\/\/difue.de\/app\/uploads\/2021\/09\/difue-logo.svg\",\"width\":200,\"height\":149,\"caption\":\"Digitalf\u00fchrerschein (DiF\u00fc)\"},\"image\":{\"@id\":\"https:\/\/difue.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/DsiN-Digitalf\u00fchrerschein-DiF\u00fc\/100079074183260\/\",\"https:\/\/www.instagram.com\/dsin_digitalfuehrerschein\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/difue.de\/en\/#\/schema\/person\/561da257ed73a0e0a7b309ed668c2e2f\",\"name\":\"DiF\u00fc-Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/difue.de\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g\",\"caption\":\"DiF\u00fc-Redaktion\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Je j\u00fcnger, desto digitaler \u2013 stimmt das? &#8226; Digitalf\u00fchrerschein (DiF\u00fc)","description":"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/","og_locale":"en_US","og_type":"article","og_title":"Je j\u00fcnger, desto digitaler \u2013 stimmt das?","og_description":"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich?","og_url":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/","og_site_name":"Digitalf\u00fchrerschein (DiF\u00fc)","article_publisher":"https:\/\/www.facebook.com\/people\/DsiN-Digitalf%c3%bchrerschein-DiF%c3%bc\/100079074183260\/","article_published_time":"2023-12-14T07:00:00+00:00","article_modified_time":"2023-12-14T09:59:13+00:00","author":"DiF\u00fc-Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DiF\u00fc-Redaktion","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/#article","isPartOf":{"@id":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/"},"author":{"name":"DiF\u00fc-Redaktion","@id":"https:\/\/difue.de\/en\/#\/schema\/person\/561da257ed73a0e0a7b309ed668c2e2f"},"headline":"Je j\u00fcnger, desto digitaler \u2013 stimmt das?","datePublished":"2023-12-14T07:00:00+00:00","dateModified":"2023-12-14T09:59:13+00:00","mainEntityOfPage":{"@id":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/"},"wordCount":411,"commentCount":0,"publisher":{"@id":"https:\/\/difue.de\/en\/#organization"},"keywords":["Digitalkompetenzen","Internet","Social Media"],"articleSection":["Devices &amp; Tools","Mythos des Monats"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/","url":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/","name":"Je j\u00fcnger, desto digitaler \u2013 stimmt das? &#8226; Digitalf\u00fchrerschein (DiF\u00fc)","isPartOf":{"@id":"https:\/\/difue.de\/en\/#website"},"datePublished":"2023-12-14T07:00:00+00:00","dateModified":"2023-12-14T09:59:13+00:00","description":"Babys, die auf Smartphones wischen, noch bevor sie ihren ersten Schritt machen \u2013 ein Mythos, der sich hartn\u00e4ckig h\u00e4lt. Doch wie technisch versiert ist die Gen Z wirklich?","breadcrumb":{"@id":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/difue.de\/en\/news\/mythos-des-monats\/mythos-des-monats-digital-natives\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/difue.de\/en\/startseite\/"},{"@type":"ListItem","position":2,"name":"Je j\u00fcnger, desto digitaler \u2013 stimmt das?"}]},{"@type":"WebSite","@id":"https:\/\/difue.de\/en\/#website","url":"https:\/\/difue.de\/en\/","name":"Digitalf\u00fchrerschein (DiF\u00fc)","description":"","publisher":{"@id":"https:\/\/difue.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/difue.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/difue.de\/en\/#organization","name":"Digitalf\u00fchrerschein (DiF\u00fc)","url":"https:\/\/difue.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/difue.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/difue.de\/app\/uploads\/2021\/09\/difue-logo.svg","contentUrl":"https:\/\/difue.de\/app\/uploads\/2021\/09\/difue-logo.svg","width":200,"height":149,"caption":"Digitalf\u00fchrerschein (DiF\u00fc)"},"image":{"@id":"https:\/\/difue.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/DsiN-Digitalf\u00fchrerschein-DiF\u00fc\/100079074183260\/","https:\/\/www.instagram.com\/dsin_digitalfuehrerschein\/"]},{"@type":"Person","@id":"https:\/\/difue.de\/en\/#\/schema\/person\/561da257ed73a0e0a7b309ed668c2e2f","name":"DiF\u00fc-Redaktion","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/difue.de\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f53ae98a098ac8e91c22c4cad6773d087e0c7938120a8a098aa93d0f488aaa56?s=96&d=mm&r=g","caption":"DiF\u00fc-Redaktion"}}]}},"_links":{"self":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/39288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/users\/8048"}],"replies":[{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/comments?post=39288"}],"version-history":[{"count":15,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/39288\/revisions"}],"predecessor-version":[{"id":39391,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/39288\/revisions\/39391"}],"acf:post":[{"embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/posts\/39421"}],"wp:attachment":[{"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/media?parent=39288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/categories?post=39288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/difue.de\/en\/wp-json\/wp\/v2\/tags?post=39288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}